{"id":388,"date":"2020-04-03T10:25:16","date_gmt":"2020-04-03T08:25:16","guid":{"rendered":"https:\/\/test123456.nl\/?page_id=388"},"modified":"2021-05-24T12:27:36","modified_gmt":"2021-05-24T10:27:36","slug":"essai-2","status":"publish","type":"page","link":"https:\/\/test123456.nl\/fr\/test-2\/","title":{"rendered":"Test 2 : Se rapporte au test 1"},"content":{"rendered":"<div class=\"video-shortcode\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"tRSk2LF309\"><p><a href=\"https:\/\/test123456.nl\/fr\/essai-1\/\">Test 1 : Se rapporte au test 2<\/a><\/p><\/blockquote>\n<p><iframe class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"\u00ab\u00a0Test\u00a01\u00a0:\u00a0fait r\u00e9f\u00e9rence au test\u00a02\u00a0\u00bb\u00a0- Test123456.nl\" src=\"https:\/\/test123456.nl\/test-1\/embed\/#?secret=tRSk2LF309\" data-secret=\"tRSk2LF309\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/div>","protected":false},"excerpt":{"rendered":"<p>Test 1 : Se rapporte au test 2<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-388","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Test 2: Refers to test 1 - Test123456.nl<\/title>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Test 2: Refers to test 1 - Test123456.nl\" \/>\n<meta property=\"og:description\" content=\"Test 1: Refers to test 2\" \/>\n<meta property=\"og:url\" content=\"https:\/\/test123456.nl\/fr\/essai-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Test123456.nl\" \/>\n<meta property=\"article:modified_time\" content=\"2021-05-24T10:27:36+00:00\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/test123456.nl\\\/test-2\\\/\",\"url\":\"https:\\\/\\\/test123456.nl\\\/test-2\\\/\",\"name\":\"Test 2: Refers to test 1 - Test123456.nl\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/test123456.nl\\\/#website\"},\"datePublished\":\"2020-04-03T08:25:16+00:00\",\"dateModified\":\"2021-05-24T10:27:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/test123456.nl\\\/test-2\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/test123456.nl\\\/test-2\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/test123456.nl\\\/test-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/test123456.nl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Test 2: Refers to test 1\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/test123456.nl\\\/#website\",\"url\":\"https:\\\/\\\/test123456.nl\\\/\",\"name\":\"Test123456.nl\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/test123456.nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Test 2 : fait r\u00e9f\u00e9rence au test 1 - Test123456.nl","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"fr_FR","og_type":"article","og_title":"Test 2: Refers to test 1 - Test123456.nl","og_description":"Test 1: Refers to test 2","og_url":"https:\/\/test123456.nl\/fr\/essai-2\/","og_site_name":"Test123456.nl","article_modified_time":"2021-05-24T10:27:36+00:00","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/test123456.nl\/test-2\/","url":"https:\/\/test123456.nl\/test-2\/","name":"Test 2 : fait r\u00e9f\u00e9rence au test 1 - Test123456.nl","isPartOf":{"@id":"https:\/\/test123456.nl\/#website"},"datePublished":"2020-04-03T08:25:16+00:00","dateModified":"2021-05-24T10:27:36+00:00","breadcrumb":{"@id":"https:\/\/test123456.nl\/test-2\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/test123456.nl\/test-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/test123456.nl\/test-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/test123456.nl\/"},{"@type":"ListItem","position":2,"name":"Test 2: Refers to test 1"}]},{"@type":"WebSite","@id":"https:\/\/test123456.nl\/#website","url":"https:\/\/test123456.nl\/","name":"Test123456.nl","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/test123456.nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/test123456.nl\/fr\/wp-json\/wp\/v2\/pages\/388","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/test123456.nl\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/test123456.nl\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/test123456.nl\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/test123456.nl\/fr\/wp-json\/wp\/v2\/comments?post=388"}],"version-history":[{"count":11,"href":"https:\/\/test123456.nl\/fr\/wp-json\/wp\/v2\/pages\/388\/revisions"}],"predecessor-version":[{"id":720,"href":"https:\/\/test123456.nl\/fr\/wp-json\/wp\/v2\/pages\/388\/revisions\/720"}],"wp:attachment":[{"href":"https:\/\/test123456.nl\/fr\/wp-json\/wp\/v2\/media?parent=388"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}